{"id":109,"count":2,"description":"","link":"https:\/\/alone.vertical01.com\/ar\/tag\/give-ar\/","name":"\u064a\u0639\u0637\u064a","slug":"give-ar","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u064a\u0639\u0637\u064a Archives - alone.vertical01.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alone.vertical01.com\/ar\/tag\/give-ar\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u064a\u0639\u0637\u064a Archives - alone.vertical01.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alone.vertical01.com\/ar\/tag\/give-ar\/\" \/>\n<meta property=\"og:site_name\" content=\"alone.vertical01.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/tag\\\/give-ar\\\/\",\"url\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/tag\\\/give-ar\\\/\",\"name\":\"\u064a\u0639\u0637\u064a Archives - alone.vertical01.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/tag\\\/give-ar\\\/#breadcrumb\"},\"inLanguage\":\"ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/tag\\\/give-ar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u064a\u0639\u0637\u064a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/\",\"name\":\"alone.vertical01.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/#organization\",\"name\":\"alone.vertical01.com\",\"url\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alone.vertical01.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/site-logo-min.png\",\"contentUrl\":\"https:\\\/\\\/alone.vertical01.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/site-logo-min.png\",\"width\":337,\"height\":104,\"caption\":\"alone.vertical01.com\"},\"image\":{\"@id\":\"https:\\\/\\\/alone.vertical01.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u064a\u0639\u0637\u064a Archives - alone.vertical01.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alone.vertical01.com\/ar\/tag\/give-ar\/","og_locale":"ar_AR","og_type":"article","og_title":"\u064a\u0639\u0637\u064a Archives - alone.vertical01.com","og_url":"https:\/\/alone.vertical01.com\/ar\/tag\/give-ar\/","og_site_name":"alone.vertical01.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/alone.vertical01.com\/ar\/tag\/give-ar\/","url":"https:\/\/alone.vertical01.com\/ar\/tag\/give-ar\/","name":"\u064a\u0639\u0637\u064a Archives - alone.vertical01.com","isPartOf":{"@id":"https:\/\/alone.vertical01.com\/ar\/#website"},"breadcrumb":{"@id":"https:\/\/alone.vertical01.com\/ar\/tag\/give-ar\/#breadcrumb"},"inLanguage":"ar"},{"@type":"BreadcrumbList","@id":"https:\/\/alone.vertical01.com\/ar\/tag\/give-ar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alone.vertical01.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u064a\u0639\u0637\u064a"}]},{"@type":"WebSite","@id":"https:\/\/alone.vertical01.com\/ar\/#website","url":"https:\/\/alone.vertical01.com\/ar\/","name":"alone.vertical01.com","description":"","publisher":{"@id":"https:\/\/alone.vertical01.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alone.vertical01.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/alone.vertical01.com\/ar\/#organization","name":"alone.vertical01.com","url":"https:\/\/alone.vertical01.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/alone.vertical01.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/alone.vertical01.com\/wp-content\/uploads\/2024\/09\/site-logo-min.png","contentUrl":"https:\/\/alone.vertical01.com\/wp-content\/uploads\/2024\/09\/site-logo-min.png","width":337,"height":104,"caption":"alone.vertical01.com"},"image":{"@id":"https:\/\/alone.vertical01.com\/ar\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/alone.vertical01.com\/ar\/wp-json\/wp\/v2\/tags\/109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alone.vertical01.com\/ar\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/alone.vertical01.com\/ar\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/alone.vertical01.com\/ar\/wp-json\/wp\/v2\/posts?tags=109"},{"href":"https:\/\/alone.vertical01.com\/ar\/wp-json\/wp\/v2\/tribe_events?tags=109"},{"href":"https:\/\/alone.vertical01.com\/ar\/wp-json\/wp\/v2\/tec_calendar_embed?tags=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}